{"id":2441,"date":"2022-11-04T18:11:27","date_gmt":"2022-11-04T17:11:27","guid":{"rendered":"https:\/\/ctalker.org\/?p=2441"},"modified":"2022-11-04T18:15:23","modified_gmt":"2022-11-04T17:15:23","slug":"novemberi-kurbli-musor","status":"publish","type":"post","link":"https:\/\/ctalker.org\/en\/2022\/11\/04\/novemberi-kurbli-musor\/","title":{"rendered":"Novemberi Kurbli M\u0171sor"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img data-opt-id=87492906  fetchpriority=\"high\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/mladjxeqsxgv.i.optimole.com\/cb:B3zE.b136\/w:724\/h:1024\/q:mauto\/f:best\/https:\/\/ctalker.org\/wp-content\/uploads\/2022\/11\/Novemberi-KUrbli-plakat-png.png\" alt=\"\" class=\"wp-image-2442\" srcset=\"https:\/\/mladjxeqsxgv.i.optimole.com\/cb:B3zE.b136\/w:724\/h:1024\/q:mauto\/f:best\/https:\/\/ctalker.org\/wp-content\/uploads\/2022\/11\/Novemberi-KUrbli-plakat-png.png 724w, https:\/\/mladjxeqsxgv.i.optimole.com\/cb:B3zE.b136\/w:212\/h:300\/q:mauto\/f:best\/https:\/\/ctalker.org\/wp-content\/uploads\/2022\/11\/Novemberi-KUrbli-plakat-png.png 212w, https:\/\/mladjxeqsxgv.i.optimole.com\/cb:B3zE.b136\/w:763\/h:1080\/q:mauto\/f:best\/https:\/\/ctalker.org\/wp-content\/uploads\/2022\/11\/Novemberi-KUrbli-plakat-png.png 768w, https:\/\/mladjxeqsxgv.i.optimole.com\/cb:B3zE.b136\/w:763\/h:1080\/q:mauto\/f:best\/https:\/\/ctalker.org\/wp-content\/uploads\/2022\/11\/Novemberi-KUrbli-plakat-png.png 1086w, https:\/\/mladjxeqsxgv.i.optimole.com\/cb:B3zE.b136\/w:763\/h:1080\/q:mauto\/f:best\/https:\/\/ctalker.org\/wp-content\/uploads\/2022\/11\/Novemberi-KUrbli-plakat-png.png 1414w, https:\/\/mladjxeqsxgv.i.optimole.com\/cb:B3zE.b136\/w:763\/h:1080\/q:mauto\/f:best\/dpr:2\/https:\/\/ctalker.org\/wp-content\/uploads\/2022\/11\/Novemberi-KUrbli-plakat-png.png 2x\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":2445,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[8,9],"tags":[],"class_list":["post-2441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kurbli","category-kurbli-filmklub"],"featured_image_src":"https:\/\/mladjxeqsxgv.i.optimole.com\/cb:B3zE.b136\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/ctalker.org\/wp-content\/uploads\/2022\/11\/Majus.jpg","featured_image_src_square":"https:\/\/mladjxeqsxgv.i.optimole.com\/cb:B3zE.b136\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/ctalker.org\/wp-content\/uploads\/2022\/11\/Majus.jpg","author_info":{"display_name":"Kari","author_link":"https:\/\/ctalker.org\/en\/author\/karina\/"},"_links":{"self":[{"href":"https:\/\/ctalker.org\/en\/wp-json\/wp\/v2\/posts\/2441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ctalker.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ctalker.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ctalker.org\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ctalker.org\/en\/wp-json\/wp\/v2\/comments?post=2441"}],"version-history":[{"count":1,"href":"https:\/\/ctalker.org\/en\/wp-json\/wp\/v2\/posts\/2441\/revisions"}],"predecessor-version":[{"id":2444,"href":"https:\/\/ctalker.org\/en\/wp-json\/wp\/v2\/posts\/2441\/revisions\/2444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ctalker.org\/en\/wp-json\/wp\/v2\/media\/2445"}],"wp:attachment":[{"href":"https:\/\/ctalker.org\/en\/wp-json\/wp\/v2\/media?parent=2441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ctalker.org\/en\/wp-json\/wp\/v2\/categories?post=2441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ctalker.org\/en\/wp-json\/wp\/v2\/tags?post=2441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}